{"id":10367,"date":"2025-05-15T17:15:18","date_gmt":"2025-05-15T20:15:18","guid":{"rendered":"https:\/\/saec.sp.gov.br\/?p=10367"},"modified":"2025-05-15T17:15:18","modified_gmt":"2025-05-15T20:15:18","slug":"interdicao-na-rua-13-de-maio-em-16-05-2025","status":"publish","type":"post","link":"https:\/\/saec.sp.gov.br\/index.php\/2025\/05\/15\/interdicao-na-rua-13-de-maio-em-16-05-2025\/","title":{"rendered":"INTERDI\u00c7\u00c3O NA RUA 13 DE MAIO EM 16\/05\/2025"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\">Aten\u00e7\u00e3o, motoristas e moradores!<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Nesta sexta-feira, dia16, a rua 13 de Maio, no trecho entre as ruas Taquaritinga e Rio Preto, estar\u00e1 interditada a partir das 7h para obras de drenagem.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">A libera\u00e7\u00e3o do tr\u00e2nsito est\u00e1 prevista para \u00e0s 17h, assim que os trabalhos forem finalizados.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Programe-se com anteced\u00eancia e utilize rotas alternativas durante o per\u00edodo.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Contamos com a compreens\u00e3o e colabora\u00e7\u00e3o de todos!<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aten\u00e7\u00e3o, motoristas e moradores! Nesta sexta-feira, dia16, a rua 13 de Maio, no trecho entre as ruas Taquaritinga e Rio Preto, estar\u00e1 interditada a partir das 7h para obras de drenagem. A libera\u00e7\u00e3o do tr\u00e2nsito est\u00e1 prevista para \u00e0s 17h, assim que os trabalhos forem finalizados. Programe-se com anteced\u00eancia e utilize rotas alternativas durante o [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":10074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>INTERDI\u00c7\u00c3O NA RUA 13 DE MAIO EM 16\/05\/2025 - SAEC Superintendencia de Agua e Esgoto de Catanduva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saec.sp.gov.br\/index.php\/2025\/05\/15\/interdicao-na-rua-13-de-maio-em-16-05-2025\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INTERDI\u00c7\u00c3O NA RUA 13 DE MAIO EM 16\/05\/2025 - SAEC Superintendencia de Agua e Esgoto de Catanduva\" \/>\n<meta property=\"og:description\" content=\"Aten\u00e7\u00e3o, motoristas e moradores! Nesta sexta-feira, dia16, a rua 13 de Maio, no trecho entre as ruas Taquaritinga e Rio Preto, estar\u00e1 interditada a partir das 7h para obras de drenagem. A libera\u00e7\u00e3o do tr\u00e2nsito est\u00e1 prevista para \u00e0s 17h, assim que os trabalhos forem finalizados. Programe-se com anteced\u00eancia e utilize rotas alternativas durante o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saec.sp.gov.br\/index.php\/2025\/05\/15\/interdicao-na-rua-13-de-maio-em-16-05-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"SAEC Superintendencia de Agua e Esgoto de Catanduva\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T20:15:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/saec.sp.gov.br\/wp-content\/uploads\/2025\/03\/INTERDICAO-DE-RUA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"526\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Karla Sibro\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"0 minuto\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/saec.sp.gov.br\/#website\",\"url\":\"https:\/\/saec.sp.gov.br\/\",\"name\":\"SAEC Superintendencia de Agua e Esgoto de Catanduva\",\"description\":\"SAEC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/saec.sp.gov.br\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/saec.sp.gov.br\/index.php\/2025\/05\/15\/interdicao-na-rua-13-de-maio-em-16-05-2025\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/saec.sp.gov.br\/wp-content\/uploads\/2025\/03\/INTERDICAO-DE-RUA.jpg\",\"width\":526,\"height\":526},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/saec.sp.gov.br\/index.php\/2025\/05\/15\/interdicao-na-rua-13-de-maio-em-16-05-2025\/#webpage\",\"url\":\"https:\/\/saec.sp.gov.br\/index.php\/2025\/05\/15\/interdicao-na-rua-13-de-maio-em-16-05-2025\/\",\"name\":\"INTERDI\\u00c7\\u00c3O NA RUA 13 DE MAIO EM 16\/05\/2025 - SAEC Superintendencia de Agua e Esgoto de Catanduva\",\"isPartOf\":{\"@id\":\"https:\/\/saec.sp.gov.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/saec.sp.gov.br\/index.php\/2025\/05\/15\/interdicao-na-rua-13-de-maio-em-16-05-2025\/#primaryimage\"},\"datePublished\":\"2025-05-15T20:15:18+00:00\",\"dateModified\":\"2025-05-15T20:15:18+00:00\",\"author\":{\"@id\":\"https:\/\/saec.sp.gov.br\/#\/schema\/person\/0adeb299f513c0b2fcb1812012e43dea\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/saec.sp.gov.br\/index.php\/2025\/05\/15\/interdicao-na-rua-13-de-maio-em-16-05-2025\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/saec.sp.gov.br\/#\/schema\/person\/0adeb299f513c0b2fcb1812012e43dea\",\"name\":\"Karla Sibro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","amp_validity":null,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/10367"}],"collection":[{"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=10367"}],"version-history":[{"count":1,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/10367\/revisions"}],"predecessor-version":[{"id":10368,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/10367\/revisions\/10368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/media\/10074"}],"wp:attachment":[{"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=10367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=10367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=10367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}