{"id":5828,"date":"2023-01-21T14:10:00","date_gmt":"2023-01-21T17:10:00","guid":{"rendered":"http:\/\/saec.sp.gov.br\/?p=5828"},"modified":"2023-01-23T14:11:38","modified_gmt":"2023-01-23T17:11:38","slug":"plantao-da-saec-13","status":"publish","type":"post","link":"https:\/\/saec.sp.gov.br\/index.php\/2023\/01\/21\/plantao-da-saec-13\/","title":{"rendered":"PLANT\u00c3O DA SAEC\u00a0"},"content":{"rendered":"\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xdj266r x126k92a\">\n<div dir=\"auto\">\u00a0<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\u00a0S\u00e1bado de chuva! Mas isso n\u00e3o foi empecilho para equipe da SAEC.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Colaboradores n\u00e3o mediram esfor\u00e7os para atender os chamados:<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\u00a0desobstru\u00e7\u00e3o de rede de esgoto, na rua Rio Grande do Sul &#8211; Higien\u00f3polis.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\u00a0Reparo na rua Rafael Fernandes Cervantes, no Nova Catanduva II, para conter vazamento de \u00e1gua .<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">\u00a0Manuten\u00e7\u00e3o de po\u00e7os de visita de \u00e1guas pluviais em determinados bairros.<\/div>\n<div dir=\"auto\">21\/01\/2023<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":5829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,43],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PLANT\u00c3O DA SAEC\u00a0 - SAEC Superintendencia de Agua e Esgoto de Catanduva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saec.sp.gov.br\/index.php\/2023\/01\/21\/plantao-da-saec-13\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PLANT\u00c3O DA SAEC\u00a0 - SAEC Superintendencia de Agua e Esgoto de Catanduva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saec.sp.gov.br\/index.php\/2023\/01\/21\/plantao-da-saec-13\/\" \/>\n<meta property=\"og:site_name\" content=\"SAEC Superintendencia de Agua e Esgoto de Catanduva\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-21T17:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-23T17:11:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/saec.sp.gov.br\/wp-content\/uploads\/2023\/01\/326780843_5820604384654719_2475519582766882355_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Katia Muller\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"0 minuto\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/saec.sp.gov.br\/#website\",\"url\":\"https:\/\/saec.sp.gov.br\/\",\"name\":\"SAEC Superintendencia de Agua e Esgoto de Catanduva\",\"description\":\"SAEC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/saec.sp.gov.br\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/saec.sp.gov.br\/index.php\/2023\/01\/21\/plantao-da-saec-13\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/saec.sp.gov.br\/wp-content\/uploads\/2023\/01\/326780843_5820604384654719_2475519582766882355_n.jpg\",\"width\":720,\"height\":867},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/saec.sp.gov.br\/index.php\/2023\/01\/21\/plantao-da-saec-13\/#webpage\",\"url\":\"https:\/\/saec.sp.gov.br\/index.php\/2023\/01\/21\/plantao-da-saec-13\/\",\"name\":\"PLANT\\u00c3O DA SAEC\\u00a0 - SAEC Superintendencia de Agua e Esgoto de Catanduva\",\"isPartOf\":{\"@id\":\"https:\/\/saec.sp.gov.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/saec.sp.gov.br\/index.php\/2023\/01\/21\/plantao-da-saec-13\/#primaryimage\"},\"datePublished\":\"2023-01-21T17:10:00+00:00\",\"dateModified\":\"2023-01-23T17:11:38+00:00\",\"author\":{\"@id\":\"https:\/\/saec.sp.gov.br\/#\/schema\/person\/50ef0d9dd88bbbcefe39443548103bbb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/saec.sp.gov.br\/index.php\/2023\/01\/21\/plantao-da-saec-13\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/saec.sp.gov.br\/#\/schema\/person\/50ef0d9dd88bbbcefe39443548103bbb\",\"name\":\"Katia Muller\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","amp_validity":null,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/5828"}],"collection":[{"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=5828"}],"version-history":[{"count":1,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/5828\/revisions"}],"predecessor-version":[{"id":5830,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/5828\/revisions\/5830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/media\/5829"}],"wp:attachment":[{"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=5828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=5828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saec.sp.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=5828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}